{"id":12978,"date":"2018-12-19T08:27:00","date_gmt":"2018-12-19T07:27:00","guid":{"rendered":"https:\/\/www.sonnenseite.com\/politik\/eu-verschaerft-abgasgrenzwerte.html"},"modified":"2018-12-19T08:27:00","modified_gmt":"2018-12-19T07:27:00","slug":"eu-verschaerft-abgasgrenzwerte","status":"publish","type":"post","link":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/","title":{"rendered":"EU versch\u00e4rft Abgasgrenzwerte"},"content":{"rendered":"<p>Europ&auml;isches Parlament, Ministerrat und EU-Kommission haben sich auf strengere CO2-Grenzwerte f&uuml;r Pkw und leichte Nutzfahrzeuge ab 2030 geeinigt und gehen dabei sogar weiter, als die Mitgliedsstaaten zugestehen wollten. Die Autoindustrie warnt vor Jobverlusten, den Gr&uuml;nen gehen die Vorgaben nicht weit genug.<\/p>\n<p> <!--more--> <\/p>\n<p>Nach <a href=\"https:\/\/www.klimareporter.de\/europaische-union\/eu-co2-reduktion-fuer-verkehrs-vertagt\" target=\"_blank\" rel=\"noopener noreferrer\">langen Verhandlungen<\/a>  haben sich das Europaparlament, die EU-Mitgliedsstaaten und die  Europ&auml;ische Kommission am gestrigen Montagabend auf strengere  Emissionsgrenzwerte f&uuml;r Autos geeinigt. Bis 2030 sollen Pkw-Hersteller  die CO<sub>2<\/sub>-Emissionen ihrer Neuwagen im Vergleich zu 2021 um 37,5 Prozent senken.<\/p>\n<p>F&uuml;r leichte Nutzfahrzeuge gilt ein etwas abgeschw&auml;chtes Ziel von 31  Prozent weniger Emissionen. Bereits 2025 soll f&uuml;r beide Fahrzeugklassen  ein Zwischenziel von 15 Prozent Reduktion erreicht sein.<\/p>\n<p>Basis des Minderungsziels ist die bereits beschlossene Vorgabe, dass  ab 2021 Neuwagen im Flottendurchschnitt nicht mehr als 95 Gramm  Kohlendioxid pro Kilometer aussto&szlig;en d&uuml;rfen. Davon sind viele  Autohersteller noch weit entfernt.<\/p>\n<p>Entsprechend scharf fiel die Kritik der Autoindustrie an dem  gestrigen Beschluss aus. &#8222;Damit wird die europ&auml;ische Automobilindustrie  im internationalen Wettbewerb stark belastet&#8220;, <a href=\"https:\/\/www.vda.de\/de\/presse\/Pressemeldungen\/20181217-Mattes-CO2-Regulierung-fordert-zu-viel-und-foerdert-zu-wenig.html\" target=\"_blank\" rel=\"noopener noreferrer\">beschwerte <\/a>sich<a href=\"https:\/\/www.vda.de\/de\/presse\/Pressemeldungen\/20181217-Mattes-CO2-Regulierung-fordert-zu-viel-und-foerdert-zu-wenig.html\" target=\"_blank\" rel=\"noopener noreferrer\"> <\/a><a href=\"https:\/\/de.wikipedia.org\/wiki\/Bernhard_Mattes\" target=\"_blank\" rel=\"noopener noreferrer\">Bernhard Mattes<\/a>,  Pr&auml;sident des deutschen Verbands der Automobilindustrie (VDA).  Nirgendwo auf der Welt gebe es so strenge Vorgaben, so der VDA. Die  Industrie k&ouml;nne das neue Ziel technisch gar nicht erreichen.<\/p>\n<div class=\"content-add\">\n<div class=\"moduletable \">\n<div class=\"bannergroup\"> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>Die Bundesregierung hatte bis zuletzt versucht, die strengeren  Vorgaben aufzuweichen. Sie wollte ein Reduktionsziel von nur 30 Prozent  durchsetzen, um so die deutschen Autobauer erneut zu sch&uuml;tzen.<\/p>\n<p>Mit dem Vorschlag von 30 Prozent Minus war die EU-Kommission in die  Verhandlungen gegangen. Das EU-Parlament hatte sich hingegen f&uuml;r <a href=\"https:\/\/www.klimareporter.de\/verkehr\/eu-parlament-will-scharfe-klimavorgaben-fuer-autos\" target=\"_blank\" rel=\"noopener noreferrer\">40 Prozent<\/a> Reduktion stark gemacht, die Abgeordneten im Umweltausschuss wollten sogar <a href=\"https:\/\/www.klimareporter.de\/verkehr\/eu-umweltpolitiker-wollen-bis-2030-halb-so-dreckige-autos\" target=\"_blank\" rel=\"noopener noreferrer\">45 Prozent<\/a>. Umweltverb&auml;nde fordern 60 bis 70 Prozent.<\/p>\n<p>Die Umweltminister im EU-Ministerrat hatten sich <a href=\"https:\/\/www.klimareporter.de\/verkehr\/eu-umweltminister-einigen-sich-auf-co2-grenzwerte\" target=\"_blank\" rel=\"noopener noreferrer\">f&uuml;r 35 Prozent<\/a>  ausgesprochen. Die gestrige Einigung geht nun &uuml;ber die Position der  Mitgliedsstaaten hinaus und liegt genau zwischen Rat und Parlament.<\/p>\n<p><strong>&#8222;Das wird den Auto-Standort Europa st&auml;rken, nicht schw&auml;chen&#8220;<\/strong><\/p>\n<p>Die europ&auml;ischen Gr&uuml;nen begr&uuml;&szlig;ten den Beschluss, obwohl der Fraktion  im Europaparlament die Ziele nicht weit genug gehen. &#8222;Dieser Kompromiss  ist das Beste, was mit den Regierungen der EU-Mitgliedsstaaten zu  erreichen war&#8220;, <a href=\"https:\/\/www.greens-efa.eu\/de\/artikel\/press\/grosse-koalition-bremst-klimaschutz-aus\/\" target=\"_blank\" rel=\"noopener noreferrer\">erkl&auml;rte<\/a> die Abgeordnete <a href=\"https:\/\/de.wikipedia.org\/wiki\/Rebecca_Harms\" target=\"_blank\" rel=\"noopener noreferrer\">Rebecca Harms<\/a>.<\/p>\n<p>&#8222;Nur wenige Tage nach Abschluss der <a href=\"https:\/\/www.klimareporter.de\/tag\/cop-24\" target=\"_blank\" rel=\"noopener noreferrer\">Klimakonferenz in Katowice<\/a>  bleibt die Vereinbarung jedoch weit hinter dem zur&uuml;ck, was notwendig  w&auml;re, um ernsthaft auf die Ziele des Pariser Klimaabkommens  hinzuarbeiten&#8220;, sagte Harms. F&uuml;r das Erreichen der Klimaziele ist der  Verkehrssektor essenziell, macht er doch beinahe ein Viertel der  europ&auml;ischen Emissionen aus.<\/p>\n<p>Besonders von der Bundesregierung sind die Gr&uuml;nen entt&auml;uscht. Die  Schwerf&auml;lligkeit der schwarz-roten Koalition bremse den Klimaschutz  immer wieder aus, sagte Harms. Zwischenzeitlich waren die Verhandlungen  wegen fehlender Zustimmung aus Deutschland <a href=\"https:\/\/www.klimareporter.de\/europaische-union\/eu-co2-reduktion-fuer-verkehrs-vertagt\" target=\"_blank\" rel=\"noopener noreferrer\">ins Stocken geraten<\/a>.<\/p>\n<p>Bundesumweltministerin Svenja Schulze (SPD) lobte indes die Einigung  als &#8222;gutes Ergebnis&#8220;. Europa habe sich einmal mehr handlungsf&auml;hig  gezeigt. &#8222;Alle haben sich in dieser schwierigen Frage aufeinander  zubewegt&#8220;, sagte Schulze. Der Beschluss bringe Klimaschutz und  Zukunftsjobs voran.<\/p>\n<p>&#8222;Die Autoindustrie wird sich zwar anstrengen m&uuml;ssen&#8220;, sagte die  Ministerin. &#8222;Aber dieser Beschluss wird den Auto-Standort Europa nicht  schw&auml;chen, sondern st&auml;rken. Mit den neuen Grenzwerten bekommen wir  starke Anreize f&uuml;r effizientere Fahrzeuge und den Umstieg auf eine neue,  saubere Mobilit&auml;t.&#8220;<\/p>\n<p>Damit die neuen Ziele erreicht werden k&ouml;nnen, m&uuml;ssen deutlich weniger  Autos mit Verbrennungsmotoren auf den Stra&szlig;en fahren. Ungef&auml;hr jeder  dritte Neuwagen muss einen Elektromotor haben. F&uuml;r Autofahrer habe die  neue Regelung Vorteile, weil sie Spritkosten sparen k&ouml;nnten, sagte <a href=\"https:\/\/www.transportenvironment.org\/people\/greg-archer\" target=\"_blank\" rel=\"noopener noreferrer\">Greg Archer<\/a> vom europ&auml;ischen Dachverband Transport &amp; Environment (T&amp;A).<\/p>\n<p>Zudem seien die strengeren Grenzwerte eine Chance, mit China Schritt  zu halten und dadurch Arbeitspl&auml;tze in Europa zu sichern. T&amp;A  rechnet mit mehr als <a href=\"https:\/\/www.transportenvironment.org\/press\/eu-gives-boost-affordable-cleaner-cars-deal-not-good-enough-planet\" target=\"_blank\" rel=\"noopener noreferrer\">200.000 neuen Stellen<\/a>.<\/p>\n<p>Damit die neue Regelung in Kraft tritt, m&uuml;ssen Rat und Parlament dem Ergebnis noch formal zustimmen.<\/p>\n<h5 class=\"green\">Quelle<\/h5>\n<p>Der Bericht wurde von<br \/>\nder&nbsp;<a href=\"https:\/\/www.klimareporter.de\/verkehr\/eu-verschaerft-abgasgrenzwerte\" target=\"_blank\" rel=\"noopener noreferrer\">Redaktion &bdquo;klimareporter.de&ldquo; (Svea Busse) 2018<\/a>&nbsp;verfasst &#8211; der Artikel<br \/>\ndarf nicht ohne Genehmigung&nbsp;(<a href=\"mailto:post@klimareporter.de\">post@klimareporter.de<\/a>) weiterverbreitet werden!&nbsp;<\/p>\n<div class=\"shariff shariff-align-flex-start shariff-widget-align-flex-start\"><div class=\"ShariffHeadline\">Diese Meldung teilen<\/div><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8;border-radius:1%\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fpolitik%2Feu-verschaerft-abgasgrenzwerte%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959;border-radius:1%\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fpolitik%2Feu-verschaerft-abgasgrenzwerte%2F&text=EU%20versch%C3%A4rft%20Abgasgrenzwerte\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a;border-radius:1%\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fpolitik%2Feu-verschaerft-abgasgrenzwerte%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf;border-radius:1%\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fpolitik%2Feu-verschaerft-abgasgrenzwerte%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button printer shariff-nocustomcolor\" style=\"background-color:#a8a8a8;border-radius:1%\"><a href=\"javascript:window.print()\" title=\"drucken\" aria-label=\"drucken\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 30 32\"><path fill=\"#999\" d=\"M6.8 27.4h16v-4.6h-16v4.6zM6.8 16h16v-6.8h-2.8q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-11.4v11.4zM27.4 17.2q0-0.5-0.3-0.8t-0.8-0.4-0.8 0.4-0.3 0.8 0.3 0.8 0.8 0.3 0.8-0.3 0.3-0.8zM29.7 17.2v7.4q0 0.2-0.2 0.4t-0.4 0.2h-4v2.8q0 0.7-0.5 1.2t-1.2 0.5h-17.2q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-4q-0.2 0-0.4-0.2t-0.2-0.4v-7.4q0-1.4 1-2.4t2.4-1h1.2v-9.7q0-0.7 0.5-1.2t1.2-0.5h12q0.7 0 1.6 0.4t1.3 0.8l2.7 2.7q0.5 0.5 0.9 1.4t0.4 1.6v4.6h1.1q1.4 0 2.4 1t1 2.4z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8;border-radius:1%\"><a href=\"mailto:?body=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fpolitik%2Feu-verschaerft-abgasgrenzwerte%2F&subject=EU%20versch%C3%A4rft%20Abgasgrenzwerte\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Europ&auml;isches Parlament, Ministerrat und EU-Kommission haben sich auf strengere CO2-Grenzwerte f&uuml;r Pkw und leichte Nutzfahrzeuge ab [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-12978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EU versch\u00e4rft Abgasgrenzwerte - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt<\/title>\n<meta name=\"description\" content=\"Europ&auml;isches Parlament, Ministerrat und EU-Kommission haben sich auf strengere CO2-Grenzwerte f&uuml;r Pkw und leichte Nutzfahrzeuge ab 2030 geeinigt\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EU versch\u00e4rft Abgasgrenzwerte - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt\" \/>\n<meta property=\"og:description\" content=\"Europ&auml;isches Parlament, Ministerrat und EU-Kommission haben sich auf strengere CO2-Grenzwerte f&uuml;r Pkw und leichte Nutzfahrzeuge ab 2030 geeinigt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/\" \/>\n<meta property=\"og:site_name\" content=\"Sonnenseite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Franz-Alt-SONNENSEITECOM\/221072987903953?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-19T07:27:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sbade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@franzalt\" \/>\n<meta name=\"twitter:site\" content=\"@franzalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"sbade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/\"},\"author\":{\"name\":\"sbade\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#\/schema\/person\/6df44691cd9a70d99e140e1116ee8771\"},\"headline\":\"EU versch\u00e4rft Abgasgrenzwerte\",\"datePublished\":\"2018-12-19T07:27:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/\"},\"wordCount\":694,\"publisher\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg\",\"articleSection\":[\"Politik\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/\",\"url\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/\",\"name\":\"EU versch\u00e4rft Abgasgrenzwerte - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt\",\"isPartOf\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg\",\"datePublished\":\"2018-12-19T07:27:00+00:00\",\"description\":\"Europ&auml;isches Parlament, Ministerrat und EU-Kommission haben sich auf strengere CO2-Grenzwerte f&uuml;r Pkw und leichte Nutzfahrzeuge ab 2030 geeinigt\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#primaryimage\",\"url\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg\",\"contentUrl\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg\",\"width\":770,\"height\":420,\"caption\":\"Depositphotos | ruigsantos | Emissionsstarke Fahrzeuge sollen durch die Regelung vom Markt gedr&auml;ngt werden. F&uuml;r solche Autos haben die Hersteller jahrelang Werbung gemacht.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.sonnenseite.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EU versch\u00e4rft Abgasgrenzwerte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#website\",\"url\":\"https:\/\/www.sonnenseite.com\/de\/\",\"name\":\"Sonnenseite\",\"description\":\"\u00d6kologische Kommunikation mit Franz Alt\",\"publisher\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sonnenseite.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#organization\",\"name\":\"Sonnenseite\",\"url\":\"https:\/\/www.sonnenseite.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2020\/05\/Sonnenseite_Logo.png\",\"contentUrl\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2020\/05\/Sonnenseite_Logo.png\",\"width\":377,\"height\":90,\"caption\":\"Sonnenseite\"},\"image\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/Franz-Alt-SONNENSEITECOM\/221072987903953?fref=ts\",\"https:\/\/x.com\/franzalt\",\"http:\/\/www.youtube.com\/results?search_query&amp;amp;quot;franz_alt&amp;amp;quot;&amp;amp;amp;amp;search_type&amp;amp;amp;amp;aq=f\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#\/schema\/person\/6df44691cd9a70d99e140e1116ee8771\",\"name\":\"sbade\",\"sameAs\":[\"https:\/\/www.sonnenseite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EU versch\u00e4rft Abgasgrenzwerte - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt","description":"Europ&auml;isches Parlament, Ministerrat und EU-Kommission haben sich auf strengere CO2-Grenzwerte f&uuml;r Pkw und leichte Nutzfahrzeuge ab 2030 geeinigt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/","og_locale":"de_DE","og_type":"article","og_title":"EU versch\u00e4rft Abgasgrenzwerte - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt","og_description":"Europ&auml;isches Parlament, Ministerrat und EU-Kommission haben sich auf strengere CO2-Grenzwerte f&uuml;r Pkw und leichte Nutzfahrzeuge ab 2030 geeinigt","og_url":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/","og_site_name":"Sonnenseite","article_publisher":"https:\/\/www.facebook.com\/pages\/Franz-Alt-SONNENSEITECOM\/221072987903953?fref=ts","article_published_time":"2018-12-19T07:27:00+00:00","og_image":[{"width":770,"height":420,"url":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg","type":"image\/jpeg"}],"author":"sbade","twitter_card":"summary_large_image","twitter_creator":"@franzalt","twitter_site":"@franzalt","twitter_misc":{"Verfasst von":"sbade","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#article","isPartOf":{"@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/"},"author":{"name":"sbade","@id":"https:\/\/www.sonnenseite.com\/de\/#\/schema\/person\/6df44691cd9a70d99e140e1116ee8771"},"headline":"EU versch\u00e4rft Abgasgrenzwerte","datePublished":"2018-12-19T07:27:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/"},"wordCount":694,"publisher":{"@id":"https:\/\/www.sonnenseite.com\/de\/#organization"},"image":{"@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg","articleSection":["Politik"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/","url":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/","name":"EU versch\u00e4rft Abgasgrenzwerte - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt","isPartOf":{"@id":"https:\/\/www.sonnenseite.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#primaryimage"},"image":{"@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg","datePublished":"2018-12-19T07:27:00+00:00","description":"Europ&auml;isches Parlament, Ministerrat und EU-Kommission haben sich auf strengere CO2-Grenzwerte f&uuml;r Pkw und leichte Nutzfahrzeuge ab 2030 geeinigt","breadcrumb":{"@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#primaryimage","url":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg","contentUrl":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2018\/12\/Auto_Auspuff_ruigsantos_.jpg","width":770,"height":420,"caption":"Depositphotos | ruigsantos | Emissionsstarke Fahrzeuge sollen durch die Regelung vom Markt gedr&auml;ngt werden. F&uuml;r solche Autos haben die Hersteller jahrelang Werbung gemacht."},{"@type":"BreadcrumbList","@id":"https:\/\/www.sonnenseite.com\/de\/politik\/eu-verschaerft-abgasgrenzwerte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sonnenseite.com\/de\/"},{"@type":"ListItem","position":2,"name":"EU versch\u00e4rft Abgasgrenzwerte"}]},{"@type":"WebSite","@id":"https:\/\/www.sonnenseite.com\/de\/#website","url":"https:\/\/www.sonnenseite.com\/de\/","name":"Sonnenseite","description":"\u00d6kologische Kommunikation mit Franz Alt","publisher":{"@id":"https:\/\/www.sonnenseite.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sonnenseite.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.sonnenseite.com\/de\/#organization","name":"Sonnenseite","url":"https:\/\/www.sonnenseite.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sonnenseite.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2020\/05\/Sonnenseite_Logo.png","contentUrl":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2020\/05\/Sonnenseite_Logo.png","width":377,"height":90,"caption":"Sonnenseite"},"image":{"@id":"https:\/\/www.sonnenseite.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Franz-Alt-SONNENSEITECOM\/221072987903953?fref=ts","https:\/\/x.com\/franzalt","http:\/\/www.youtube.com\/results?search_query&amp;amp;quot;franz_alt&amp;amp;quot;&amp;amp;amp;amp;search_type&amp;amp;amp;amp;aq=f"]},{"@type":"Person","@id":"https:\/\/www.sonnenseite.com\/de\/#\/schema\/person\/6df44691cd9a70d99e140e1116ee8771","name":"sbade","sameAs":["https:\/\/www.sonnenseite.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/posts\/12978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/comments?post=12978"}],"version-history":[{"count":0,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/posts\/12978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/media\/12976"}],"wp:attachment":[{"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/media?parent=12978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/categories?post=12978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/tags?post=12978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}