{"id":94191,"date":"2023-09-22T03:15:00","date_gmt":"2023-09-22T01:15:00","guid":{"rendered":"https:\/\/www.sonnenseite.com\/?p=94191"},"modified":"2023-10-03T13:27:30","modified_gmt":"2023-10-03T11:27:30","slug":"neuer-kunststoff-loest-sich-in-meerwasser-auf","status":"publish","type":"post","link":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/","title":{"rendered":"Neuer Kunststoff l\u00f6st sich in Meerwasser auf"},"content":{"rendered":"\n<p>Kunststoffe der Zukunft werden keine Gefahr f\u00fcr die Meere mehr sein. Wenn sie mit Salzwasser in Ber\u00fchrung kommen, zerfallen sie in ihre molek\u00fclgro\u00dfen Bestandteile. <\/p>\n\n\n\n<p>Ruirui Qiao vom\u00a0<a href=\"https:\/\/aibn.uq.edu.au\/\" target=\"_blank\" rel=\"noreferrer noopener\">Australian Institute for Bioengineering and Nanotechnology<\/a>, das an der\u00a0<a href=\"https:\/\/www.uq.edu.au\/\" target=\"_blank\" rel=\"noreferrer noopener\">University of Queensland<\/a>\u00a0angesiedelt ist, entwickelt diese Plastikversion gemeinsam mit Kollegen vom\u00a0<a href=\"http:\/\/english.ciac.cas.cn\/au\/\" target=\"_blank\" rel=\"noreferrer noopener\">Changchun Institute of Applied Chemistry<\/a>\u00a0(CIAC) in China, das auch eine Dependance in Australien hat.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Vernetzung mit spezieller Technik<\/h4>\n\n\n\n<p>Das Kunstst\u00fcck soll mit einer speziellen Polymerisationstechnik gelingen. Polymerisation ist die Vernetzung der Monomere, der vereinzelten Bausteine, aus denen Plastik besteht, zu einem stabilen Werkstoff. &#8222;Unsere Ozeane werden durch langlebige Plastikbeh\u00e4lter, T\u00fcten und sogar Mikroplastik belastet, was eine erhebliche Bedrohung f\u00fcr \u00d6kosysteme sowie Millionen von Seev\u00f6geln und S\u00e4ugetieren darstellt&#8220;, so Qiao.<\/p>\n\n\n\n<p>Ihre Forschergruppe arbeitet mit einem Monomer, das von Forschern des CIAC entwickelt worden ist. Dieses vernetzt sie mithilfe des 3D-Drucks, einem Verfahren, das f\u00fcr die Massenproduktion allerdings ungeeignet ist. Immerhin konnte sie so zeigen, dass die Herstellung eines Polymers, das in Salzwasser abgebaut wird, m\u00f6glich ist.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Von Ringform zum linearen Polymer<\/h4>\n\n\n\n<p>F\u00fcr die gro\u00dftechnische Produktion setzt Qiao auf ein Verfahren namens Ring\u00f6ffnende Polymerisation. Dabei wird aus einem ringf\u00f6rmigen Monomer ein lineares Polymer. Damit lassen sich die mechanische Festigkeit und die Form der Kunststoffe pr\u00e4zise steuern, sodass der Zerfall in Meerwasser garantiert ist. Dieser Prozess dauert allerdings einige Zeit, sodass dem normalen Gebrauch von Beh\u00e4ltern aus diesem Kunststoff nichts entgegensteht.<\/p>\n\n\n\n<p>Binnen f\u00fcnf Jahren wollen die Experten eine neue Produktlinie in Australien und China auf den Markt bringen, die herk\u00f6mmliche Kunststoffe ersetzt und einen Markt f\u00fcr biologisch abbaubare Produkte erschlie\u00dft, der bis dahin voraussichtlich 9,5 Mrd. Dollar \u00fcbersteigt. &#8222;Wirksame, im Meerwasser abbaubare Polymerkunststoffe werden verhindern, dass die Ozeane weiter verschmutzt und die Gesundheit der \u00d6kosysteme auf der ganzen Welt verbessert werden &#8222;, sagt Qiao.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/aibn.uq.edu.au\/article\/2023\/09\/salt-water-degradable-plastics-help-save-our-oceans\">&#8222;Salt water-degradable plastics to help save our oceans&#8220; | The University of Queensland 2023<\/a><\/li>\n<\/ul>\n\n\n<h5 class=\"green\">Quelle<\/h5>\r\n\n\n\n<p>Der Bericht wurde von der\u00a0<a href=\"https:\/\/www.pressetext.com\/news\/neuer-kunststoff-loest-sich-in-meerwasser-auf.html\">Redaktion &#8222;pressetext.com\u201c (Wolfgang Kempkens) 2023<\/a>\u00a0verfasst \u2013 der Artikel darf\u00a0nicht ohne\u00a0<a href=\"mailto:redaktion@pressetext.com\">Genehmigung\u00a0weiterverbreitet<\/a>\u00a0werden!\u00a0<\/p>\n<div class=\"shariff shariff-align-flex-start shariff-widget-align-flex-start\"><div class=\"ShariffHeadline\">Diese Meldung teilen<\/div><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8;border-radius:1%\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fwissenschaft%2Fneuer-kunststoff-loest-sich-in-meerwasser-auf%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959;border-radius:1%\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fwissenschaft%2Fneuer-kunststoff-loest-sich-in-meerwasser-auf%2F&text=Neuer%20Kunststoff%20l%C3%B6st%20sich%20in%20Meerwasser%20auf\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a;border-radius:1%\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fwissenschaft%2Fneuer-kunststoff-loest-sich-in-meerwasser-auf%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf;border-radius:1%\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fwissenschaft%2Fneuer-kunststoff-loest-sich-in-meerwasser-auf%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button printer shariff-nocustomcolor\" style=\"background-color:#a8a8a8;border-radius:1%\"><a href=\"javascript:window.print()\" title=\"drucken\" aria-label=\"drucken\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 30 32\"><path fill=\"#999\" d=\"M6.8 27.4h16v-4.6h-16v4.6zM6.8 16h16v-6.8h-2.8q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-11.4v11.4zM27.4 17.2q0-0.5-0.3-0.8t-0.8-0.4-0.8 0.4-0.3 0.8 0.3 0.8 0.8 0.3 0.8-0.3 0.3-0.8zM29.7 17.2v7.4q0 0.2-0.2 0.4t-0.4 0.2h-4v2.8q0 0.7-0.5 1.2t-1.2 0.5h-17.2q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-4q-0.2 0-0.4-0.2t-0.2-0.4v-7.4q0-1.4 1-2.4t2.4-1h1.2v-9.7q0-0.7 0.5-1.2t1.2-0.5h12q0.7 0 1.6 0.4t1.3 0.8l2.7 2.7q0.5 0.5 0.9 1.4t0.4 1.6v4.6h1.1q1.4 0 2.4 1t1 2.4z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button mailto shariff-nocustomcolor\" style=\"background-color:#a8a8a8;border-radius:1%\"><a href=\"mailto:?body=https%3A%2F%2Fwww.sonnenseite.com%2Fde%2Fwissenschaft%2Fneuer-kunststoff-loest-sich-in-meerwasser-auf%2F&subject=Neuer%20Kunststoff%20l%C3%B6st%20sich%20in%20Meerwasser%20auf\" title=\"Per E-Mail versenden\" aria-label=\"Per E-Mail versenden\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\";border-radius:1%; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#999\" d=\"M32 12.7v14.2q0 1.2-0.8 2t-2 0.9h-26.3q-1.2 0-2-0.9t-0.8-2v-14.2q0.8 0.9 1.8 1.6 6.5 4.4 8.9 6.1 1 0.8 1.6 1.2t1.7 0.9 2 0.4h0.1q0.9 0 2-0.4t1.7-0.9 1.6-1.2q3-2.2 8.9-6.1 1-0.7 1.8-1.6zM32 7.4q0 1.4-0.9 2.7t-2.2 2.2q-6.7 4.7-8.4 5.8-0.2 0.1-0.7 0.5t-1 0.7-0.9 0.6-1.1 0.5-0.9 0.2h-0.1q-0.4 0-0.9-0.2t-1.1-0.5-0.9-0.6-1-0.7-0.7-0.5q-1.6-1.1-4.7-3.2t-3.6-2.6q-1.1-0.7-2.1-2t-1-2.5q0-1.4 0.7-2.3t2.1-0.9h26.3q1.2 0 2 0.8t0.9 2z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Kunststoffe der Zukunft werden keine Gefahr f\u00fcr die Meere mehr sein. Wenn sie mit Salzwasser in [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-94191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wissenschaft"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Neuer Kunststoff l\u00f6st sich in Meerwasser auf - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt<\/title>\n<meta name=\"description\" content=\"Kunststoffe der Zukunft werden keine Gefahr f\u00fcr die Meere mehr sein. Wenn sie mit Salzwasser in Ber\u00fchrung kommen, zerfallen sie in ihre molek\u00fclgro\u00dfen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuer Kunststoff l\u00f6st sich in Meerwasser auf - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt\" \/>\n<meta property=\"og:description\" content=\"Kunststoffe der Zukunft werden keine Gefahr f\u00fcr die Meere mehr sein. Wenn sie mit Salzwasser in Ber\u00fchrung kommen, zerfallen sie in ihre molek\u00fclgro\u00dfen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/\" \/>\n<meta property=\"og:site_name\" content=\"Sonnenseite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Franz-Alt-SONNENSEITECOM\/221072987903953?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-22T01:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-03T11:27:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bigi Alt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@franzalt\" \/>\n<meta name=\"twitter:site\" content=\"@franzalt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bigi Alt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/\"},\"author\":{\"name\":\"Bigi Alt\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#\/schema\/person\/50fda0e926597684c7cc6695238a4eb9\"},\"headline\":\"Neuer Kunststoff l\u00f6st sich in Meerwasser auf\",\"datePublished\":\"2023-09-22T01:15:00+00:00\",\"dateModified\":\"2023-10-03T11:27:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/\"},\"wordCount\":349,\"publisher\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg\",\"articleSection\":[\"Wissenschaft\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/\",\"url\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/\",\"name\":\"Neuer Kunststoff l\u00f6st sich in Meerwasser auf - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt\",\"isPartOf\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg\",\"datePublished\":\"2023-09-22T01:15:00+00:00\",\"dateModified\":\"2023-10-03T11:27:30+00:00\",\"description\":\"Kunststoffe der Zukunft werden keine Gefahr f\u00fcr die Meere mehr sein. Wenn sie mit Salzwasser in Ber\u00fchrung kommen, zerfallen sie in ihre molek\u00fclgro\u00dfen\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#primaryimage\",\"url\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg\",\"contentUrl\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg\",\"width\":770,\"height\":420,\"caption\":\"ClipDealer.com | whitcomberd\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.sonnenseite.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neuer Kunststoff l\u00f6st sich in Meerwasser auf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#website\",\"url\":\"https:\/\/www.sonnenseite.com\/de\/\",\"name\":\"Sonnenseite\",\"description\":\"\u00d6kologische Kommunikation mit Franz Alt\",\"publisher\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sonnenseite.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#organization\",\"name\":\"Sonnenseite\",\"url\":\"https:\/\/www.sonnenseite.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2020\/05\/Sonnenseite_Logo.png\",\"contentUrl\":\"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2020\/05\/Sonnenseite_Logo.png\",\"width\":377,\"height\":90,\"caption\":\"Sonnenseite\"},\"image\":{\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/Franz-Alt-SONNENSEITECOM\/221072987903953?fref=ts\",\"https:\/\/x.com\/franzalt\",\"http:\/\/www.youtube.com\/results?search_query&amp;amp;quot;franz_alt&amp;amp;quot;&amp;amp;amp;amp;search_type&amp;amp;amp;amp;aq=f\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sonnenseite.com\/de\/#\/schema\/person\/50fda0e926597684c7cc6695238a4eb9\",\"name\":\"Bigi Alt\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neuer Kunststoff l\u00f6st sich in Meerwasser auf - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt","description":"Kunststoffe der Zukunft werden keine Gefahr f\u00fcr die Meere mehr sein. Wenn sie mit Salzwasser in Ber\u00fchrung kommen, zerfallen sie in ihre molek\u00fclgro\u00dfen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/","og_locale":"de_DE","og_type":"article","og_title":"Neuer Kunststoff l\u00f6st sich in Meerwasser auf - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt","og_description":"Kunststoffe der Zukunft werden keine Gefahr f\u00fcr die Meere mehr sein. Wenn sie mit Salzwasser in Ber\u00fchrung kommen, zerfallen sie in ihre molek\u00fclgro\u00dfen","og_url":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/","og_site_name":"Sonnenseite","article_publisher":"https:\/\/www.facebook.com\/pages\/Franz-Alt-SONNENSEITECOM\/221072987903953?fref=ts","article_published_time":"2023-09-22T01:15:00+00:00","article_modified_time":"2023-10-03T11:27:30+00:00","og_image":[{"width":770,"height":420,"url":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg","type":"image\/jpeg"}],"author":"Bigi Alt","twitter_card":"summary_large_image","twitter_creator":"@franzalt","twitter_site":"@franzalt","twitter_misc":{"Verfasst von":"Bigi Alt","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#article","isPartOf":{"@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/"},"author":{"name":"Bigi Alt","@id":"https:\/\/www.sonnenseite.com\/de\/#\/schema\/person\/50fda0e926597684c7cc6695238a4eb9"},"headline":"Neuer Kunststoff l\u00f6st sich in Meerwasser auf","datePublished":"2023-09-22T01:15:00+00:00","dateModified":"2023-10-03T11:27:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/"},"wordCount":349,"publisher":{"@id":"https:\/\/www.sonnenseite.com\/de\/#organization"},"image":{"@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg","articleSection":["Wissenschaft"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/","url":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/","name":"Neuer Kunststoff l\u00f6st sich in Meerwasser auf - Sonnenseite - \u00d6kologische Kommunikation mit Franz Alt","isPartOf":{"@id":"https:\/\/www.sonnenseite.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#primaryimage"},"image":{"@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg","datePublished":"2023-09-22T01:15:00+00:00","dateModified":"2023-10-03T11:27:30+00:00","description":"Kunststoffe der Zukunft werden keine Gefahr f\u00fcr die Meere mehr sein. Wenn sie mit Salzwasser in Ber\u00fchrung kommen, zerfallen sie in ihre molek\u00fclgro\u00dfen","breadcrumb":{"@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#primaryimage","url":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg","contentUrl":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2019\/04\/Plastik_Meer_whitcomberd.jpg","width":770,"height":420,"caption":"ClipDealer.com | whitcomberd"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sonnenseite.com\/de\/wissenschaft\/neuer-kunststoff-loest-sich-in-meerwasser-auf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sonnenseite.com\/de\/"},{"@type":"ListItem","position":2,"name":"Neuer Kunststoff l\u00f6st sich in Meerwasser auf"}]},{"@type":"WebSite","@id":"https:\/\/www.sonnenseite.com\/de\/#website","url":"https:\/\/www.sonnenseite.com\/de\/","name":"Sonnenseite","description":"\u00d6kologische Kommunikation mit Franz Alt","publisher":{"@id":"https:\/\/www.sonnenseite.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sonnenseite.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.sonnenseite.com\/de\/#organization","name":"Sonnenseite","url":"https:\/\/www.sonnenseite.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sonnenseite.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2020\/05\/Sonnenseite_Logo.png","contentUrl":"https:\/\/www.sonnenseite.com\/wp-content\/uploads\/2020\/05\/Sonnenseite_Logo.png","width":377,"height":90,"caption":"Sonnenseite"},"image":{"@id":"https:\/\/www.sonnenseite.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Franz-Alt-SONNENSEITECOM\/221072987903953?fref=ts","https:\/\/x.com\/franzalt","http:\/\/www.youtube.com\/results?search_query&amp;amp;quot;franz_alt&amp;amp;quot;&amp;amp;amp;amp;search_type&amp;amp;amp;amp;aq=f"]},{"@type":"Person","@id":"https:\/\/www.sonnenseite.com\/de\/#\/schema\/person\/50fda0e926597684c7cc6695238a4eb9","name":"Bigi Alt"}]}},"_links":{"self":[{"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/posts\/94191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/comments?post=94191"}],"version-history":[{"count":2,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/posts\/94191\/revisions"}],"predecessor-version":[{"id":94193,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/posts\/94191\/revisions\/94193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/media\/10019"}],"wp:attachment":[{"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/media?parent=94191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/categories?post=94191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sonnenseite.com\/de\/wp-json\/wp\/v2\/tags?post=94191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}